{"id":83,"count":54,"description":"","link":"https:\/\/www.neivor.com\/en\/autor\/jorge-parra\/","name":"Jorge Parra","slug":"jorge-parra","taxonomy":"autor","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.neivor.com\/en\/wp-json\/wp\/v2\/autor\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neivor.com\/en\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/www.neivor.com\/en\/wp-json\/wp\/v2\/taxonomies\/autor"}]}}